{"id":8725,"date":"2022-10-25T08:08:26","date_gmt":"2022-10-25T08:08:26","guid":{"rendered":"https:\/\/schimmel-piano.gdstest.de\/?page_id=8725"},"modified":"2025-07-07T08:42:12","modified_gmt":"2025-07-07T08:42:12","slug":"prevention-et-soin","status":"publish","type":"page","link":"https:\/\/www.schimmel-pianos.de\/fr\/werterhalt-und-pflege\/","title":{"rendered":"Entretien et maintenance"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8725\" class=\"elementor elementor-8725\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#FFFFFF\" class=\"elementor-section elementor-top-section elementor-element elementor-element-38c0666a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"38c0666a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7cf4251b\" data-id=\"7cf4251b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f517678 hero-image elementor-widget elementor-widget-image\" data-id=\"1f517678\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1500\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2.webp\" class=\"attachment-full size-full wp-image-11472\" alt=\"Pflege und Werterhalt Titelbild\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2.webp 2500w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2-300x180.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2-1024x614.webp 1024w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2-768x461.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2-1536x922.webp 1536w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2-2048x1229.webp 2048w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2-18x12.webp 18w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2-1568x941.webp 1568w\" sizes=\"auto, (max-width: 2500px) 100vw, 2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-color=\"#FFFFFF\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5ffeb1a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ffeb1a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6586b95e\" data-id=\"6586b95e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-687e5540 elementor-widget elementor-widget-spacer\" data-id=\"687e5540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-492e2032 elementor-widget elementor-widget-heading\" data-id=\"492e2032\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Werterhalt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-5f9a79f1 elementor-widget elementor-widget-heading\" data-id=\"5f9a79f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">&amp; Pflege<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1e8cdf elementor-widget elementor-widget-spacer\" data-id=\"a1e8cdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67b684c2 elementor-widget elementor-widget-text-editor\" data-id=\"67b684c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Wertvolle Tips f\u00fcr die Pflege und den Werterhalt Ihres Schimmel Pianos<\/strong><\/p><p>Ein markanter Spruch unseres Firmengr\u00fcnders Wilhelm Schimmel war: \u201eAm Ende sind unsere Instrumente immer nur so gut, wie der letzte Service Klaviertechniker, der daran gearbeitet hat\u201c. In diesem Satz steckt viel Wahres, denn hochwertige Qualit\u00e4t braucht zum Erhalt auch einen hochwertigen After Sales Service und eine ausgezeichnete Pflege.<\/p><p>Aus diesem Grund werden Schimmel Instrumente weltweit ausschlie\u00dflich \u00fcber den autorisierten Fachhandel verkauft. Dabei machen wir es zur Bedingung, dass unsere Fachhandelspartner einen ausgezeichneten After Sales Service anbieten.<\/p><p>Dar\u00fcber hinaus, k\u00f6nnen aber auch Sie einen wertvollen und wichtigen Beitrag leisten, um die Qualit\u00e4t und den Wert Ihres Instrumentes zu erhalten. Im Folgenden finden Sie daf\u00fcr n\u00fctzliche Hinweise. Verzichten Sie deshalb aber nie auf den Rat unserer autorisierten Fachhandelspartner vor Ort.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20213fc8 elementor-widget elementor-widget-spacer\" data-id=\"20213fc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10931f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10931f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71c5c06\" data-id=\"71c5c06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c252ba8 elementor-widget elementor-widget-spacer\" data-id=\"c252ba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46461e0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46461e0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ac4a93\" data-id=\"7ac4a93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-242c868 elementor-widget elementor-widget-image\" data-id=\"242c868\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Spielgefuhl-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11476\" alt=\"Werterhalt Pflege Spielgef\u00fchl\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Spielgefuhl-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Spielgefuhl-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Spielgefuhl-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Spielgefuhl.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-21a319d\" data-id=\"21a319d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-6a554f2 elementor-widget elementor-widget-heading\" data-id=\"6a554f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Spielgef\u00fchl und H\u00f6rempfinden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29cfdaa elementor-widget elementor-widget-text-editor\" data-id=\"29cfdaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die instrumentalen Qualit\u00e4ten sind f\u00fcr das Wohlbefinden beim Musizieren an Pianoforteinstrumenten von entscheidender Bedeutung. Doch nur wenn der &#8222;Wohlklang&#8220; schwingender und singender Klangk\u00f6rper mit dem &#8222;Wohlgef\u00fchl&#8220; zuverl\u00e4ssig und dynamisch reagierender Spielwerke verschmelzen, entfalten sich die M\u00f6glichkeiten zu unbeschwertem Musizieren. Energie flie\u00dft in der Natur in geordneten Kreisl\u00e4ufen, pflanzt sich fort, kehrt zur\u00fcck oder wandelt sich. In den Klangk\u00f6rpern und Spielwerken akustischer Pianoforteinstrumente ist dies nicht anders. Was den Tasten beim Spiel an Energie vermittelt wird (Kraft, Schnelligkeit und Weg der Tastenbewegung), so transformiert das Spielwerk in Beschleunigung der Hammerk\u00f6pfe. Diese \u00fcbertragen die ihnen somit innewohnende Energie auf die Klangsaiten. Damit beginnen die Klangsaiten zu schwingen. Der Klangk\u00f6rper bringt dann zu Geh\u00f6r, was in den Klangsaiten schwingt und schwebt. Jede einzelne davon produziert ihre origin\u00e4ren Frequenzen, f\u00fcgt sich ein, erg\u00e4nzt und bereichert die Klangbilder, welche sich aus der Vielzahl der miteinander schwingenden Klangsaiten entwickelt. Der Resonanzboden nimmt diese Schwingungsenergie auf, vibriert in sich st\u00e4ndig \u00e4ndernder Formen und produziert Schallwellen, welche schlie\u00dflich an das Ohr gelangen, dort in elektrische Impulse umgewandelt und damit vom Gehirn wahrnehmbar werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6a4a0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6a4a0b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37f46b5\" data-id=\"37f46b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da3c583 elementor-widget elementor-widget-spacer\" data-id=\"da3c583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c933590 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c933590\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc392d0\" data-id=\"cc392d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-a6bec76 elementor-widget elementor-widget-heading\" data-id=\"a6bec76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Spielwerk<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c223c61 elementor-widget elementor-widget-text-editor\" data-id=\"c223c61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Mit Spielart werden die wesentlichen Eigenschaften eines Spielwerks bezeichnet. Dazu z\u00e4hlen u.a. das Gef\u00fchl von Pr\u00e4zision und Geschmeidigkeit, die Sicherheit bei leisestem Spiel oder kraftvollem Fortissimo, bei rasanten L\u00e4ufen und schnellen Repetitionsfolgen, die unterschiedlichen &#8222;Spielgewichte&#8220; und vieles mehr.<\/p><p style=\"text-align: left;\">Bei intensiv gespielten Instrumenten kommen im Laufe der Jahre gerade in den mittleren Tonlagen viele Millionen Anschl\u00e4ge pro Taste zusammen. Daraus resultiert ein nat\u00fcrlicher Verschlei\u00df, der aber bei regelm\u00e4\u00dfigem Service durch qualifizierte Fachleute und einem geeigneten Standort des Instrumentes durchaus in Grenzen gehalten werden kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f40c79\" data-id=\"3f40c79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-050064c elementor-widget elementor-widget-heading\" data-id=\"050064c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hammerk\u00f6pfe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d1ba97 elementor-widget elementor-widget-text-editor\" data-id=\"5d1ba97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Dynamisch reagierende Hammerk\u00f6pfe sind f\u00fcr gute klangliche Eigenschaften von besonderer Bedeutung. Nur ein ideales Bedingungsgef\u00fcge aus flexiblen Filzschichten, einer optimalen Form und das richtige Ma\u00df an inneren Spannungen und die richte Intonation bieten die erforderlichen Voraussetzungen, den klassischen Klavierklang beim Musizieren in unz\u00e4hligen Nuancen gestalten zu k\u00f6nnen.<\/p><p style=\"text-align: left;\">Bei intensivem Spiel verh\u00e4rten sich die Filzschichten der Hammerk\u00f6pfe. Zudem ist die Abnutzung der Hammerk\u00f6pfe an ihren Aufprallpunkten ein nat\u00fcrlicher Vorgang. Schlie\u00dflich haben auch extreme Wechsel der relativen Raumluftfeuchten Einfluss auf die Spannungsverh\u00e4ltnisse in den Hammerk\u00f6pfen. Von Zeit zu Zeit lohnt sich deshalb eine Nachintonation gegebenenfalls samt Nachformen der Hammerk\u00f6pfe. Beide Arbeiten sollten nur erfahrenen Klaviertechnikern anvertraut werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8724b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8724b6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b670cb\" data-id=\"2b670cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c60d10a elementor-widget elementor-widget-spacer\" data-id=\"c60d10a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cb8a80 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cb8a80\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-78ccb7d\" data-id=\"78ccb7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-253eb34 elementor-widget elementor-widget-image\" data-id=\"253eb34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Transport-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11477\" alt=\"Werterhalt Pflege Transport\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Transport-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Transport-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Transport-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Transport.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7cdf9cb\" data-id=\"7cdf9cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-b6e5500 elementor-widget elementor-widget-heading\" data-id=\"b6e5500\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transport<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73ae874 elementor-widget elementor-widget-text-editor\" data-id=\"73ae874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Der Standortwechsel eines Fl\u00fcgels oder Klaviers mit Rollen innerhalb eines Raumes erfordert in der Regel zwei bis drei kr\u00e4ftige Personen, um das Instrument zu verschieben. Dabei sind die Rollen durch Anheben des Instrumentes etwas zu entlasten. Bei empfindlichen und glatten Fu\u00dfb\u00f6den empfiehlt es sich, das Instrument auf eine starke Textilunterlage zu stellen und dann darauf unter Entlastung der Rollen vorsichtig zu verschieben. So werden m\u00f6gliche Besch\u00e4digungen des Fu\u00dfbodens vermieden. Klaviere ohne Rollen k\u00f6nnen auf glatten Fu\u00dfb\u00f6den in der zuvor beschriebenen Weise unter Verwendung von Textilunterlagen verschoben werden, ansonsten sind die Klaviere zu tragen. Bei jedem Transport ist sorgsam drauf zu achten, dass das Instrument nicht sein Gleichgewicht verliert und umkippt. Alle Transporte von Stockwerk zu Stockwerk und au\u00dfer Haus sollten stets Fachfirmen \u00fcbertragen werden. Standortwechsel des Instruments durch Personen mit mangelnder Erfahrung oder K\u00f6rperkraft k\u00f6nnen erhebliche k\u00f6rperliche Verletzungen oder Besch\u00e4digungen am Instrument nach sich ziehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-132ce7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"132ce7b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e089ee\" data-id=\"5e089ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dec3af2 elementor-widget elementor-widget-spacer\" data-id=\"dec3af2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ff91bf elementor-section-content-middle elementor-reverse-mobile elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ff91bf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e0a0041\" data-id=\"e0a0041\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-ad58ae0 elementor-widget elementor-widget-heading\" data-id=\"ad58ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Standorte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb5e48b elementor-widget elementor-widget-text-editor\" data-id=\"bb5e48b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Fl\u00fcgel und Klaviere bieten einen gro\u00dfen Reichtum an instrumentalen Qualit\u00e4ten und sind verl\u00e4ssliche Partner. Holz, Filze und Leder begr\u00fcnden die Einzigartigkeit ihrer klanglichen und spieltechnischen Eigenschaften. Diese Naturstoffe reagieren auf das klimatische Bedingungsgef\u00fcge am Standort des Instrumentes.<\/p><p style=\"text-align: left;\">Ungeeignet sind Standorte an oder hinter Fenstern, unmittelbar vor oder \u00fcber Radiatoren oder Konvektoren bzw. direkt \u00fcber, unter oder vor Luftaustritts\u00f6ffnungen und an feuchten, kalten Au\u00dfenw\u00e4nden. Unmittelbare Sonneneinwirkung ist sch\u00e4dlich f\u00fcr Furnierfarbt\u00f6ne und Oberfl\u00e4chen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b582568\" data-id=\"b582568\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53502d0 elementor-widget elementor-widget-image\" data-id=\"53502d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Standort-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11478\" alt=\"Werterhalt Pflege Standort Klavier Wohnung\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Standort-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Standort-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Standort-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Standort.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba94d22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba94d22\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a64607d\" data-id=\"a64607d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adbe496 elementor-widget elementor-widget-spacer\" data-id=\"adbe496\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68f7c35 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68f7c35\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23a6309\" data-id=\"23a6309\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13e78bb elementor-widget elementor-widget-image\" data-id=\"13e78bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1500\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1.webp\" class=\"attachment-full size-full wp-image-3767\" alt=\"Pflege und Werterhalt Titelbild\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1.webp 2500w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1-300x180.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1-1024x614.webp 1024w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1-768x461.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1-1536x922.webp 1536w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1-2048x1229.webp 2048w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1-18x12.webp 18w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/06\/08_Pflege_und_Werterhalt_Titelbild-1-1568x941.webp 1568w\" sizes=\"auto, (max-width: 2500px) 100vw, 2500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c3f1f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c3f1f8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-95b3995\" data-id=\"95b3995\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-692153a elementor-widget elementor-widget-spacer\" data-id=\"692153a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-134360f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"134360f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-787591d\" data-id=\"787591d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#818181\" class=\"elementor-element elementor-element-ea0e816 elementor-widget elementor-widget-heading\" data-id=\"ea0e816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tipps zur Pflege<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3db5f11 elementor-widget elementor-widget-text-editor\" data-id=\"3db5f11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Tastenbel\u00e4ge sollten nur mit weichen T\u00fcchern gereinigt werden \u00b9. In keinem Fall d\u00fcrfen Reinigungsfl\u00fcssigkeiten verwendet werden, in denen Spiritus, Alkohol oder Verd\u00fcnnungsmittel anderer Art enthalten sind. Polyesterfl\u00e4chen entstauben Sie am besten durch vorsichtiges und keinesfalls h\u00e4ufiges Wischen mit einem weichen, faserfreien Tuch \u00b9. Alle andere Oberfl\u00e4chenvariationen sollten mit trockenen, fusselfreien T\u00fcchern entstaubt werden. Bei Bedarf k\u00f6nnen bew\u00e4hrte M\u00f6belreinigungsmittel \u00b2 verwendet werden, welche keinerlei aggressive Fl\u00fcssigkeiten und\/oder Schleifmittel enthalten. Metallteile an Geh\u00e4useelementen sollten grunds\u00e4tzlich nur mit einem weichen Tuch gereinigt werden. Bei hartn\u00e4ckigen Verschmutzungen gegebenenfalls Metallpflegemittel \u00b2 verwenden \u00b3.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d9e7ae\" data-id=\"1d9e7ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdfa515 elementor-widget elementor-widget-text-editor\" data-id=\"bdfa515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">\u00b9 F\u00fcr die Reinigung hat sich ein weiches Ledertuch bew\u00e4hrt, das eventuell mit einer milden Seifenlauge oder stark verd\u00fcnntem (hautschonendem) Sp\u00fclmittel wenig angefeuchtet wird.<\/p><p style=\"text-align: left;\">\u00b2 Nur Markenprodukte verwenden, deren Beschreibung sich ausdr\u00fccklich auf die zu reinigende Oberfl\u00e4che bezieht. Lassen Sie sich beraten und beachten Sie die Gebrauchsanweisung.<\/p><p style=\"text-align: left;\">\u00b3 Konzentrieren Sie den Reinigungsvorgang nur auf die Metallteile, denn auch stark verd\u00fcnnter Spiritus oder Metallpflegemittel k\u00f6nnen die Oberfl\u00e4chen der Geh\u00e4usekomponenten angreifen.<\/p><p style=\"text-align: left;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da4701f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da4701f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20aa751\" data-id=\"20aa751\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a36a98 elementor-widget elementor-widget-spacer\" data-id=\"3a36a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcb2c31 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcb2c31\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c2a908e\" data-id=\"c2a908e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3af2186 elementor-widget elementor-widget-image\" data-id=\"3af2186\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Experten-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11501\" alt=\"Werterhalt Pflege Experten Klaviatur\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Experten-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Experten-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Experten-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Experten.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f35efc0\" data-id=\"f35efc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f06dae elementor-widget elementor-widget-heading\" data-id=\"7f06dae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fachleute wissen Rat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8798e12 elementor-widget elementor-widget-text-editor\" data-id=\"8798e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Wo T\u00f6ne schwingen und klingen, k\u00f6nnen sich auch Nebenger\u00e4usche einstellen. Oft l\u00e4sst sich problemlos lokalisieren, ob diese Nebenger\u00e4usche aus dem Fl\u00fcgel oder Klavier selbst stammen oder ob deren Quelle an anderer Stelle im Umfeld des Instrumentes zu suchen ist. Fremdk\u00f6rper k\u00f6nnen versehentlich durchaus in das Instrument gelangen. Soweit leicht zug\u00e4nglich, k\u00f6nnen diese jederzeit herausgenommen werden. \u00c4rgerlicher sind kleine Gegenst\u00e4nde wie z.B. B\u00fcroklammern, Papierschnipsel, Stoffreste, Stifte, Radiergummis etc., welche die Funktion des Spielwerks beeintr\u00e4chtigen oder Ger\u00e4usche verursachen. Mit dem Aufsp\u00fcren von Fremdk\u00f6rpern oder Ger\u00e4uschquellen innerhalb des Instrumentes sollte in jedem Fall ein Fachmann beauftragt werden. Fl\u00fcssigkeiten d\u00fcrfen keinesfalls in den Klangk\u00f6rper oder in das Spielwerk gelangen, deshalb sollten auf Pianoforteinstrumenten keine Blumenvasen, Getr\u00e4nkegl\u00e4ser oder Flaschen abgestellt werden. Dringen dennoch Fl\u00fcssigkeiten in das Instrument ein, sollte ein Fachmann zur Beratung \u00fcber die erforderlichen Gegenma\u00dfnahmen konsultiert werden. Die Reinigung des Spielwerks, der Klangsaiten und der Stimmwirbel ist in jedem Fall Fachleuten zu \u00fcberlassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b97eb88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b97eb88\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b1213b\" data-id=\"3b1213b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32143d6 elementor-widget elementor-widget-spacer\" data-id=\"32143d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5154a9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5154a9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8733aab\" data-id=\"8733aab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a75469c elementor-widget elementor-widget-heading\" data-id=\"a75469c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B\u00e4nke &amp; Zubeh\u00f6r<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dfc6dd elementor-widget elementor-widget-text-editor\" data-id=\"7dfc6dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Denken Sie daran, dass richtiges und bequemes Sitzen eine wichtige Voraussetzung f\u00fcr unbeschwertes Musizieren ist. Qualitativ gute Sitzm\u00f6bel sind deshalb gerade richtig.<\/p><p style=\"text-align: left;\">Klavierm\u00f6bel und Zubeh\u00f6r h\u00e4lt ihr Fachh\u00e4ndler bereit. Dort finden Sie eine Auswahl an Sitzgelegenheiten und auch anderes Zubeh\u00f6r wie zum Beispiel Leuchten f\u00fcr Fl\u00fcgel und Klaviere, Metronome, Notenst\u00e4nder, Untersetzer zu Schonung kostbarer Fu\u00dfb\u00f6den oder Tastenl\u00e4ufer zum Schutz der Klaviatur, au\u00dferdem H\u00fcllen in allen Varianten f\u00fcr Ihr Instrument.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40c4a98\" data-id=\"40c4a98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62793cd elementor-widget elementor-widget-heading\" data-id=\"62793cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i><b>twin<\/b>tone<\/i> und Selbstspielinstrumente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b5722 elementor-widget elementor-widget-text-editor\" data-id=\"70b5722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><i><b>twin<\/b>tone<\/i> Instrumente sind klassische Fl\u00fcgel und Klaviere mit akustischer Klangerzeugung. Das zus\u00e4tzlich integrierte Digitalklavier gestattet dar\u00fcber hinaus die M\u00f6glichkeit, zu jeder Tages- und Nachtzeit auf dem Instrument auch lautlos zu musizieren oder zu \u00fcben. Standardbuchsen gestatten den Anschluss von Kopfh\u00f6rern oder Aktivlautsprechern. AUDIO Schnittstellen erm\u00f6glichen den Anschluss verschiedener HiFi-Ger\u00e4te. MIDI er\u00f6ffnet den Zugang zur Welt der Musikelektronik.<\/p><p style=\"text-align: left;\">Detaillierte Informationen zu unserem <em><strong>twin<\/strong>tone <\/em>System finden Sie hier: <i><br \/><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a6511f elementor-widget elementor-widget-spacer\" data-id=\"1a6511f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0ffe1b elementor-align-center elementor-tablet-align-left elementor-widget elementor-widget-button\" data-id=\"b0ffe1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.schimmel-pianos.de\/twin-tone\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">twintone<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77107e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77107e0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-511f7af\" data-id=\"511f7af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d57853e elementor-widget elementor-widget-spacer\" data-id=\"d57853e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c300a7d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c300a7d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-57460ac\" data-id=\"57460ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84e67f6 elementor-widget elementor-widget-image\" data-id=\"84e67f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Pedale-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11479\" alt=\"Werterhalt Pflege Pedale Wei\u00df\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Pedale-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Pedale-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Pedale-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Pedale.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-dd798d1\" data-id=\"dd798d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba69a1e elementor-widget elementor-widget-heading\" data-id=\"ba69a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pedale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d45468 elementor-widget elementor-widget-text-editor\" data-id=\"0d45468\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Das <b>rechte Pedal (Fortepedal)<\/b> wirkt bei Fl\u00fcgeln und Klavieren auf die Gesamtheit aller D\u00e4mpfer. Bei getretenem Pedal ist die D\u00e4mpferwirkung aufgehoben. Das <b>linke Pedal (una corda)<\/b> bewirkt bei Fl\u00fcgeln eine Verschiebung des Spielwerkes und bei Klavieren eine Verringerung der Anschlagsdistanz der Hammerk\u00f6pfe bis zu den Klangsaiten. Dies f\u00fchrt in beiden F\u00e4llen zu einer Klangfarbennuancierung und auch leiseren T\u00f6nen. Das <b>mittlere Pedal <\/b>aktiviert bei Fl\u00fcgeln die Tonhaltung (sostenuto), wodurch das Ausklingverhalten jener Klangsaiten nicht abged\u00e4mpft wird, deren zugeh\u00f6rige Tasten im Augenblick der Bet\u00e4tigung des Pedals bereits gedr\u00fcckt sind. Bei Klavieren mit drei Pedalen aktiviert das mittlere Pedal je nach Modell und Ausstattung entweder die <i><b>twin<\/b>tone<\/i> Stummschaltung oder die Leisespielfunktion. Bei aktivierter Leisespielfunktion schiebt sich ein Filzstreifen vor die Hammerk\u00f6pfe und d\u00e4mpft so deren Aufprall auf die Klangsaiten. Dieser Moderatorfilz unterliegt intensivem Verschlei\u00df. Bei h\u00e4ufigem Musizieren mit der Leisespielfunktion sind die Nachjustierung des Filzstreifens und auch der Ersatz abgespielter Filzstreifen unumg\u00e4nglich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59a24b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59a24b6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a5c131\" data-id=\"0a5c131\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4593b2 elementor-widget elementor-widget-spacer\" data-id=\"c4593b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8416d57 elementor-section-content-middle elementor-reverse-mobile elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8416d57\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8ace36e\" data-id=\"8ace36e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9e9e99 elementor-widget elementor-widget-heading\" data-id=\"b9e9e99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Angenehmes Raumklima<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92ee062 elementor-widget elementor-widget-text-editor\" data-id=\"92ee062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Raumklimata, in denen sich Menschen wohlf\u00fchlen, sind auch f\u00fcr Pianoforteinstrumente gut. Ein als angenehm empfundenes Raumklima kann hinsichtlich Temperatur und Luftfeuchtigkeit durchaus sehr unterschiedliche Werte aufweisen.<\/p><p style=\"text-align: left;\">Normales L\u00fcften der R\u00e4ume ist unsch\u00e4dlich. Bei Au\u00dfentemperaturen unter dem Gefrierpunkt oder sehr nassem Wetter sollte nicht \u00fcberm\u00e4\u00dfig gel\u00fcftet werden. In diesen F\u00e4llen ist anhaltende Zugluft immer sch\u00e4dlich.<\/p><p style=\"text-align: left;\">Die ideale relative Feuchte der Raumluft sollte sich in Schwankungsbreiten zwischen 40\u00a0% und 60\u00a0% bewegen. Unterschiede zwischen 35\u00a0% bis 70\u00a0% sind noch ertr\u00e4glich. Gr\u00f6\u00dfere Schwankungen f\u00fchren mit zunehmender H\u00e4ufigkeit und Intensit\u00e4t zu zunehmenden Ver\u00e4nderung der Stimmung und der Spielbarkeit des Instrumentes.<\/p><p style=\"text-align: left;\">Die ideale Temperatur der Raumluft liegt zwischen 21\u00b0 und 24\u00b0 Celsius. Auch deutlich h\u00f6here oder niedrigere Raumtemperaturen sind ohne sch\u00e4dlichen Einfluss, solange sich die relativen Luftfeuchten zwischen 35\u00a0% und 70\u00a0% bewegen. Wo die Einhaltung der zuvor als angenehm empfundenen Klimaverh\u00e4ltnisse in einem Raum nicht m\u00f6glich ist, empfiehlt sich der Einbau eines Piano Life Saver Systems. Unter<strong> <a href=\"https:\/\/www.pianolifesaver.com\/\">www.dampp-chaser.com<\/a> <\/strong>wird dazu ausf\u00fchrlich informiert.<\/p><p style=\"text-align: left;\"><b>Als einfache Grundregel gilt:<\/b><\/p><p style=\"text-align: left;\">Jede Temperaturver\u00e4nderung in einem Raum bewirkt immer eine \u00c4nderung der relativen Luftfeuchte &#8211; daraus folgt:<\/p><p style=\"text-align: left;\">Steigende Raumtemperatur (Aufheizen) = sinkende relative Luftfeuchte ; Holz und Filz trocknen<\/p><p style=\"text-align: left;\">Sinkende Raumtemperatur (Abk\u00fchlung) = steigende relative Luftfeuchte ; Holz und Filz quellen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-446d22d\" data-id=\"446d22d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdd04ff elementor-widget elementor-widget-image\" data-id=\"fdd04ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Raumklima-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11480\" alt=\"Werterhalt Pflege Raumklima\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Raumklima-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Raumklima-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Raumklima-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Raumklima.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d606cd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d606cd9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14dac6e\" data-id=\"14dac6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69b2bd5 elementor-widget elementor-widget-spacer\" data-id=\"69b2bd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-611c53d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"611c53d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-652405e\" data-id=\"652405e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f380016 elementor-widget elementor-widget-heading\" data-id=\"f380016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Das richtige Raumklima<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2976cc elementor-widget elementor-widget-text-editor\" data-id=\"c2976cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Holz, Filze und Leder sind Naturwerkstoffe. Diese Materialien reagieren auf die klimatischen Gegebenheiten im Umfeld des Instrumentes. Besondere Vorkehrungen zur Einhaltung unsch\u00e4dlicher Schwankungen der Raumtemperaturen und relativen Luftfeuchte sind deshalb zum Vorteil des Instrumentes, verbessern die Stimmstabilit\u00e4t, reduzieren negative Einfl\u00fcsse auf die Spielbarkeit, minimieren Spannungs\u00e4nderungen im Resonanzboden, schonen die Holzkomponenten des Klangk\u00f6rpers und verl\u00e4ngern die Lebensdauer des Instrumentes.<\/p><p style=\"text-align: left;\">Jede Ver\u00e4nderung der Raumtemperatur bewirkt auch immer eine \u00c4nderung der relativen Luftfeuchte. H\u00e4ufige starke und anhaltende Schwankungen der Raumtemperaturen sind zu minimieren oder zu vermeiden. Pl\u00f6tzliche und starke Temperaturwechsel (auch l\u00e4nger anhaltend), insbesondere auch schnelles und extremes Aufheizen des Raumes ist vor allem bei tiefen Au\u00dfentemperaturen zu vermeiden, da dadurch die relative Luftfeuchtigkeit innerhalb kurzer Zeit sehr stark sinkt. Raumtemperaturen unter 10\u00b0 Celsius sollten vermieden werden. Temperaturschocks sind in jedem Fall zu vermeiden (vor allem w\u00e4hrend und unmittelbar nach Transporten).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8593a49\" data-id=\"8593a49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29d9b26 elementor-widget elementor-widget-heading\" data-id=\"29d9b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontrolle der relativen Luftfeuchte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71ad5dd elementor-widget elementor-widget-text-editor\" data-id=\"71ad5dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Zur Messung der relativen Feuchten der Raumluft empfehlen wir moderne Messger\u00e4te, die auch nach Jahren korrekte Messwerte liefern.<\/p><p style=\"text-align: left;\">Achtung!<\/p><p style=\"text-align: left;\">Servicearbeiten oder Sch\u00e4den an einem Instrument, deren Ursache auf st\u00e4ndige und\/oder extreme Schwankungen der Raumtemperaturen bzw. anhaltend zu hohe\/zu niedrige relative Luftfeuchten zur\u00fcckzuf\u00fchren sind, unterliegen weder etwaigen Garantieversprechen von Schimmel oder des Fachh\u00e4ndlers noch den gesetzlichen Gew\u00e4hrleistungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a21d0a5 elementor-widget elementor-widget-image\" data-id=\"a21d0a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Luftfeuchte-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11481\" alt=\"Werterhalt Pflege Luftfeuchte Hygrometer\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Luftfeuchte-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Luftfeuchte-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Luftfeuchte-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Luftfeuchte.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3a03aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3a03aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81a5a01\" data-id=\"81a5a01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c169f54 elementor-widget elementor-widget-spacer\" data-id=\"c169f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6725e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6725e3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ef7e41\" data-id=\"7ef7e41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5527dd3\" data-id=\"5527dd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14d186f elementor-widget elementor-widget-heading\" data-id=\"14d186f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Klimaanlage f\u00fcr Pianoforteinstrumente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69a42e9 elementor-widget elementor-widget-text-editor\" data-id=\"69a42e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Piano Life Saver System von der Firma Dampp-Chaser hat sich tausendfach bew\u00e4hrt und ist vor allem dann von gro\u00dfem Vorteil, wenn auf andere Weise die Einhaltung eines angenehmen Raumklimas mit begrenzten Schwankungen von Temperaturen und relativen Luftfeuchten nicht gew\u00e4hrleistet werden kann. Durch kontinuierlich geregelte Entfeuchtung\/Befeuchtung reduziert das System die Schwankungen der relativen Luftfeuchten unmittelbar dort auf eine Bandbreite von 40\u00a0% bis 60\u00a0%, wo die Luftfeuchtigkeit direkt auf die empfindlichen Teile des Instrumentes einwirkt (Resonanzboden, Klaviatur, Mechanik, Spielbarkeit, Stimmhaltung). Damit werden die unerw\u00fcnschten Schwankungen der Ausgleichsfeuchten in Holz und Filz deutlich verringert.<\/p><p>Das Herz des Systems ist der Humidistat, der die Entfeuchtung\/Befeuchtung der Luft in kontinuierlichem Wechsel und engen Schwankungsbreiten steuert. Die Entfeuchtung erfolgt durch Heizst\u00e4be, welche die Lufttemperatur in ihrer unmittelbaren Umgebung geringf\u00fcgig erh\u00f6hen und dabei der Luft Feuchtigkeit entziehen. Die Befeuchtung der Luft erfolgt durch ein \u00fcber W\u00e4rmest\u00e4be funktionierendes Verdampfungssystem, das der Luft Feuchtigkeit zuf\u00fchrt. In beiden F\u00e4llen wird dadurch eine Zirkulation der ent-\/befeuchteten Luft im Instrument bewirkt.<\/p><p>Richtig betrieben gew\u00e4hrleistet das System bei kontinuierlichem Betrieb in aller Regel gute klimatische Bedingungen f\u00fcr das Pianoforteinstrument &#8211; und zwar weitgehend unabh\u00e4ngig von den normalerweise \u00fcblichen Schwankungen der relativen Raumfeuchten. Detaillierte Informationen sind unter<strong> <a href=\"https:\/\/www.pianolifesaver.com\/\">www.dampp-chaser.com<\/a><\/strong> abrufbar oder bei jedem Fachh\u00e4ndler erh\u00e4ltlich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c74f46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c74f46\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-474216d\" data-id=\"474216d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-033ab8b elementor-widget elementor-widget-spacer\" data-id=\"033ab8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b57bae0 elementor-section-content-middle elementor-reverse-mobile elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b57bae0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-20015e1\" data-id=\"20015e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63364c5 elementor-widget elementor-widget-heading\" data-id=\"63364c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Heizungssysteme und Klimaanlagen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35704a1 elementor-widget elementor-widget-text-editor\" data-id=\"35704a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Die jeweiligen Raumklimata weichen umso st\u00e4rker von den \u00e4u\u00dferen Klimabedingungen ab, je gr\u00f6\u00dfer die isolierenden Wirkungen der baulichen Gegebenheiten und die Einwirkung von Heizungssystemen, L\u00fcftungs- und\/oder Klimaanlagen sind. Die Vielfalt der durch die Baulichkeiten und haustechnisch gegebenen Umst\u00e4nde l\u00e4sst sich deshalb nicht in wenigen Worten beschreiben, dazu sind Fachleute zu befragen.<\/p><p style=\"text-align: left;\"><b>Radiatoren<\/b> sind zumeist unter Fenstern angebracht. Sie wirken vor allem durch Konvektionsw\u00e4rme, geben aber auch Strahlungsw\u00e4rme ab. Ein Instrument sollte nicht unmittelbar vor solchen Heizk\u00f6rpern stehen. <b>Konvektoren<\/b> befinden sich zumeist an W\u00e4nden oder in Fu\u00dfb\u00f6den und wirken fast ausschlie\u00dflich durch Konvektionsw\u00e4rme. Direkt vor oder \u00fcber solchen Heizungsquellen darf das Instrument keinesfalls aufgestellt werden. <b>Luftheizungssysteme<\/b> erzeugen in N\u00e4he der Luftaustritts\u00f6ffnungen einen kontinuierlichen Luftstrom, der bei unmittelbarer Einwirkung f\u00fcr Fl\u00fcgel und Klaviere besonders sch\u00e4dlich ist. Ein Instrument sollte keinesfalls direkt vor, unter oder \u00fcber Luftaustritts\u00f6ffnungen stehen.<\/p><p style=\"text-align: left;\"><b>Fu\u00dfbodenheizungen<\/b> bewirken mit sehr niedrigen Heiztemperaturen eine relativ geringe, gleichm\u00e4\u00dfige Luftzirkulation im Raum. Richtig dimensionierte Fu\u00dfbodenheizungen f\u00fchren unmittelbar \u00fcber dem Fu\u00dfboden zu Lufttemperaturen um 21\u00b0 bis 24\u00b0 Celsius. Die Lufttemperatur sinkt mit zunehmendem Abstand vom Fu\u00dfboden. Die Temperatur der aufsteigenden Luft als auch die Strahlungsw\u00e4rme haben deshalb auf Fl\u00fcgel nur geringen Einfluss. Bei Klavieren empfiehlt sich eventuell eine W\u00e4rmeisolierung zwischen dem Fu\u00dfboden und dem Sockel des Instrumentes. Der Fachh\u00e4ndler wei\u00df dazu Rat. <b>Einfache Luftbefeuchtungssysteme<\/b> sind nur an Standorten mit nachhaltig sehr niedrigen relativen Luftfeuchten sinnvoll, wenn die Systeme ausreichend dimensioniert sind, zuverl\u00e4ssig arbeiten und Schwankungen der relativen Luftfeuchten unter 35\u00a0% verhindern. <b>Vollklimaanlagen<\/b> sind dann von Vorteil f\u00fcr gute Fl\u00fcgel und Klaviere, wenn sich die in den klimatisierten R\u00e4umen vorherrschende relativen Luftfeuchten in einer Bandbreite von 40\u00a0% bis 60\u00a0% bewegen und l\u00fcftungsbedingte Schwankungen schnell ausgleichen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4e79737\" data-id=\"4e79737\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffa0fc4 elementor-widget elementor-widget-image\" data-id=\"ffa0fc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Klimaanlagen-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11482\" alt=\"Werterhalt Pflege Klimaanlagen\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Klimaanlagen-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Klimaanlagen-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Klimaanlagen-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Klimaanlagen.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed97cb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed97cb0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-032082a\" data-id=\"032082a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1d33ab elementor-widget elementor-widget-spacer\" data-id=\"b1d33ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d98240 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d98240\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34fcc08\" data-id=\"34fcc08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4103b64 elementor-widget elementor-widget-heading\" data-id=\"4103b64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entsorgung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4862a43 elementor-widget elementor-widget-text-editor\" data-id=\"4862a43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Beachten Sie bei jeder Entsorgung, dass landestypische beh\u00f6rdliche Vorschriften und\/oder gesetzliche Auflagen zu ber\u00fccksichtigen sind. Die Entsorgung aller elektronischen\/elektrischen Komponenten muss gesetzeskonform erfolgen. Mehr Informationen erhalten Sie von Ihrem Fachh\u00e4ndler.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e87acda\" data-id=\"e87acda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bee872b elementor-widget elementor-widget-heading\" data-id=\"bee872b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sicherheitshinweise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f90cf8 elementor-widget elementor-widget-text-editor\" data-id=\"7f90cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Pianoforteinstrumente, B\u00e4nke, Hocker und St\u00fchle sind weder Turnger\u00e4te f\u00fcr Kinder noch eignen sie sich als Ersatz f\u00fcr Leitern oder Trittstufen. Das \u00d6ffnen und Schlie\u00dfen von Deckeln sowie die sichere Positionierung der Deckelst\u00fctzen erfordert Sorgfalt und setzt ausreichende Kraft und K\u00f6rpergr\u00f6\u00dfe voraus. Kinder wie auch Erwachsene mit unzureichender K\u00f6rperkraft sollten insbesondere Fl\u00fcgeldeckel nicht \u00f6ffnen oder schlie\u00dfen. Bei der Justierung h\u00f6henverstellbarer Sitzpolster d\u00fcrfen Finger nicht unter das Sitzpolster oder in den Verstellmechanismus geraten. Demontierbare B\u00e4nke sind vom Fachh\u00e4ndler sachgerecht zu montieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df1448c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df1448c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5942ff4\" data-id=\"5942ff4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b91d81 elementor-widget elementor-widget-spacer\" data-id=\"8b91d81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2375cfb elementor-section-content-middle elementor-reverse-mobile elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2375cfb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f08fc70\" data-id=\"f08fc70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3a3d98 elementor-widget elementor-widget-heading\" data-id=\"f3a3d98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Haftungsausschl\u00fcsse<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8aa6aa4 elementor-widget elementor-widget-text-editor\" data-id=\"8aa6aa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Die hier enthaltenen Informationen, insbesondere die gegebenen Hinweise und Empfehlungen zur Sicherheit, zum Standort, zum Transport, zum richtigen Raumklima und zum Service beruhen auf langj\u00e4hrigen Erfahrungen. Trotz sorgf\u00e4ltiger und gewissenhafter Bearbeitung \u00fcbernehmen jedoch Schimmel und ihre Beauftragten keine Gew\u00e4hrleistung f\u00fcr ihre Richtigkeit und Vollst\u00e4ndigkeit und auch keine Haftung f\u00fcr eventuelle Personen- oder Sachsch\u00e4den, Wertverluste oder sonstige Nachteile, seien sie direkter oder indirekter Art, die sich eventuell aus einer Befolgung der vorstehenden Hinweise und Empfehlungen ergeben k\u00f6nnten.<\/p>\n<p style=\"text-align: left;\">Jede Haftung von Schimmel, ihrer Beauftragten oder von Fachh\u00e4ndlern f\u00fcr eventuelle Personen- oder Sachsch\u00e4den, Wertverluste oder sonstige Nachteile, die eine direkt, indirekte oder sp\u00e4tere Folge der Missachtung der Sicherheitshinweise und Empfehlungen auf dieser Seite oder das Resultat eines unsachgem\u00e4\u00dfen Transports oder Umgangs mit dem Instrument oder Teilen davon einschlie\u00dflich der elektrischen\/elektronischen Zusatzausstattungen sind oder auf mangelhaftem oder fehlendem Service oder auf sch\u00e4dlichen Umwelteinfl\u00fcssen oder klimatischen Bedingungen beruhen, ist ausdr\u00fccklich ausgeschlossen. Soweit die vorstehenden Haftungsausschl\u00fcsse in einigen L\u00e4ndern gesetzlich beschr\u00e4nkt sein sollen, kommen sie dort im Einzelfall in dem gesetzlich m\u00f6glichen Umfang zur Wirkung. Etwaige Anspr\u00fcche sind der H\u00f6he nach in jedem Fall auf maximal den Betrag des Kaufpreises des Instrumentes beschr\u00e4nkt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d1dd694\" data-id=\"d1dd694\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5345ba elementor-widget elementor-widget-image\" data-id=\"a5345ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Warnhinweis-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11483\" alt=\"Werterhalt Pflege Warnhinweis\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Warnhinweis-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Warnhinweis-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Warnhinweis-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Warnhinweis.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e87049d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e87049d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ce41d7\" data-id=\"6ce41d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe64e2f elementor-widget elementor-widget-spacer\" data-id=\"fe64e2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ac8fc8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ac8fc8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-95fec04\" data-id=\"95fec04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2aeb1a elementor-widget elementor-widget-image\" data-id=\"d2aeb1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Service-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-11484\" alt=\"Werterhalt Pflege Service Mitarbeiter\" srcset=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Service-768x576.webp 768w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Service-300x225.webp 300w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Service-16x12.webp 16w, https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/SCH_Werterhalt_Pflege_Service.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7a5beb7\" data-id=\"7a5beb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5d0458 elementor-widget elementor-widget-heading\" data-id=\"c5d0458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Empfehlungen zum Service<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-165e20e elementor-widget elementor-widget-text-editor\" data-id=\"165e20e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Die Empfehlungen sind als allgemeine Orientierung zu verstehen und k\u00f6nnen keinesfalls die individuelle Beratung durch den Fachmann ersetzen. Bitte holen Sie im Zweifelsfall den Rat des Fachh\u00e4ndlers oder eines qualifizierten Technikers ein.<\/p><p style=\"text-align: left;\">Die empfohlenen Servicearbeiten h\u00e4ngen nach Umfang und Zeitpunkt davon ab, welche Anspr\u00fcche an Stimmung, Intonation und Spielart gestellt werden, wie h\u00e4ufig und wie intensiv das Instrument gespielt wird und welchen klimatischen Einfl\u00fcssen es ausgesetzt ist. Servicearbeiten sollten Sie Fachleuten \u00fcberlassen. Die Sch\u00e4den und M\u00e4ngel, die Nichtfachleute verursachen k\u00f6nnen, sind oft nur mit erheblichem Aufwand wieder zu reparieren. Bitte achten Sie darauf, dass nicht aufgef\u00fchrte, aber durchgef\u00fchrte Servicearbeiten dokumentiert werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ae7d91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ae7d91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34d629d\" data-id=\"34d629d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8715ab1 elementor-widget elementor-widget-spacer\" data-id=\"8715ab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-170b8a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"170b8a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ce27f44\" data-id=\"ce27f44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21969bd elementor-widget elementor-widget-menu-anchor\" data-id=\"21969bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"SN\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78a43b4 elementor-widget elementor-widget-heading\" data-id=\"78a43b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Baujahr und Seriennummer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a02153 elementor-widget elementor-widget-text-editor\" data-id=\"2a02153\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Bestimmung des Alters Ihres Instrumentes kann \u00fcber die Seriennummer vorgenommen werden. Da die Seriennummern aufgrund der unterschiedlichen Herstellungsprozesse der einzelnen Modelle nicht immer chronologisch vergeben werden k\u00f6nnen, l\u00e4\u00dft sich das Alter \u00fcber unsere Suchfunktion nur ungef\u00e4hr eingrenzen und kann mitunter erheblich vom hier angegebenen Jahr abweichen. Deshalb ist die Angabe auf unserer Websiten-Suchfunktion ohne Gew\u00e4hr.<\/p><p><br \/>Geben Sie den Zahlenbereich ein, der der Seriennummer Ihres Instruments entspricht, um das ungef\u00e4hre Baujahr herauszufinden:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8943e6 elementor-widget elementor-widget-spacer\" data-id=\"e8943e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-696523e elementor-button-align-end elementor-widget elementor-widget-form\" data-id=\"696523e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_type&quot;:&quot;none&quot;,&quot;step_icon_shape&quot;:&quot;none&quot;,&quot;button_width&quot;:&quot;100&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"8725\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"696523e\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Schimmel Piano\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-serialnumber elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[serialnumber]\" id=\"form-field-serialnumber\" class=\"elementor-field-textual elementor-size-sm\">\n\t\t\t\t\t\t\t\t\t<option value=\"1\">1<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"2-400 \">2-400 <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"401-800\">401-800<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"801-1000\">801-1000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"1.001-1.500\">1.001-1.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"1.501-2.300\">1.501-2.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"2.301-3.300\">2.301-3.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"3.301-4.300\">3.301-4.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"4.301-5.300\">4.301-5.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"5.301-6.300\">5.301-6.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"6.301-7.300\">6.301-7.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"7.301-8.300\">7.301-8.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"8.301-9.300\">8.301-9.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"9.301-10.300\">9.301-10.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"10.301-11.400\">10.301-11.400<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"11.401-12.500\">11.401-12.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"12.501-13.700\">12.501-13.700<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"13.701-15.000\">13.701-15.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"15.001-16.200\">15.001-16.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"16.201-17.300\">16.201-17.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"17.301-18.500\">17.301-18.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"18.501-19.600\">18.501-19.600<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"19.601-20.200\">19.601-20.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"20.201-20.800\">20.201-20.800<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"20.801-21.400\">20.801-21.400<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"21.401-21.800\">21.401-21.800<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"21.801-22.100\">21.801-22.100<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"22.101-22.300\">22.101-22.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"22.301-22.900\">22.301-22.900<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"22.901-24.500\">22.901-24.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"24.501-28.900\">24.501-28.900<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"28.901-35.600\">28.901-35.600<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"35.601-41.500\">35.601-41.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"41.501-50.000\">41.501-50.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"50.001-60.900\">50.001-60.900<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"60.901-73.700\">60.901-73.700<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"73.701-87.200\">73.701-87.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"87.201-101.200\">87.201-101.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"101.201-115.700\">101.201-115.700<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"115.701-123.100\">115.701-123.100<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"123.101-130.700\">123.101-130.700<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"130.701-138.400\">130.701-138.400<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"138.401-146.200\">138.401-146.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"146.201-154.200\">146.201-154.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"154.201-162.500\">154.201-162.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"162.501-171.000\">162.501-171.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"171.001-180.000\">171.001-180.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"180.001-189.500\">180.001-189.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"189.501-199.000\">189.501-199.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"199.001-209.000\">199.001-209.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"209.001-219.000\">209.001-219.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"219.001-229.000\">219.001-229.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"229.001-238.000\">229.001-238.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"238.001-247.500\">238.001-247.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"247.501-256.000\">247.501-256.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"256.001-264.000\">256.001-264.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"264.001-271.500\">264.001-271.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"271.501-278.500\">271.501-278.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"278.501-286.000\">278.501-286.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"286.001-293.500\">286.001-293.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"293.501-300.500\">293.501-300.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"300.501-307.000\">300.501-307.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"307.001-313.000\">307.001-313.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"313.001-318.500\">313.001-318.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"318.501-323.500\">318.501-323.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"323.501-327.500\">323.501-327.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"327.501-331.000\">327.501-331.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"331.001-334.500\">331.001-334.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"334.501-338.500\">334.501-338.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"338.501-342.500\">338.501-342.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"342.501-346.000\">342.501-346.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"346.001-349.500\">346.001-349.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"349.501-352.500\">349.501-352.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"352.501-355.000\">352.501-355.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"355.001-357.700\">355.001-357.700<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"357.701-359.500\">357.701-359.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"359.501-361.400\">359.501-361.400<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"361.401-363.200\">361.401-363.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"363.201-365.000\">363.201-365.000<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"365.001-367.100\">365.001-367.100<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"367.101-368.800\">367.101-368.800<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"368.801-370.500\">368.801-370.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"370.501-372.200\">370.501-372.200<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"372.201-373.300\">372.201-373.300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"373.301-374.400\">373.301-374.400<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"374.401-375.500\">374.401-375.500<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"375.501-376.600\">375.501-376.600<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1885 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1885\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1885\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1885-0\" name=\"form_fields[serial1885]\"> <label for=\"form-field-serial1885-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1890 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1890\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1886-1890\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1890-0\" name=\"form_fields[serial1890]\"> <label for=\"form-field-serial1890-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1892 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1892\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1891-1892\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1892-0\" name=\"form_fields[serial1892]\"> <label for=\"form-field-serial1892-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1894 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1894\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1893-1894\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1894-0\" name=\"form_fields[serial1894]\"> <label for=\"form-field-serial1894-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1896 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1896\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1895-1896\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1896-0\" name=\"form_fields[serial1896]\"> <label for=\"form-field-serial1896-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1898 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1898\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1897-1898\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1898-0\" name=\"form_fields[serial1898]\"> <label for=\"form-field-serial1898-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1900 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1900\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1899-1900\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1900-0\" name=\"form_fields[serial1900]\"> <label for=\"form-field-serial1900-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1902 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1902\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1901-1902\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1902-0\" name=\"form_fields[serial1902]\"> <label for=\"form-field-serial1902-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1904 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1904\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1903-1904\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1904-0\" name=\"form_fields[serial1904]\"> <label for=\"form-field-serial1904-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1906 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1906\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1905-1906\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1906-0\" name=\"form_fields[serial1906]\"> <label for=\"form-field-serial1906-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1908 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1908\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1907-1908\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1908-0\" name=\"form_fields[serial1908]\"> <label for=\"form-field-serial1908-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1910 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1910\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1909-1910\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1910-0\" name=\"form_fields[serial1910]\"> <label for=\"form-field-serial1910-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1912 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1912\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1911-1912\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1912-0\" name=\"form_fields[serial1912]\"> <label for=\"form-field-serial1912-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1914 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1914\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1913-1914\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1914-0\" name=\"form_fields[serial1914]\"> <label for=\"form-field-serial1914-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1916 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1916\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1915-1916\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1916-0\" name=\"form_fields[serial1916]\"> <label for=\"form-field-serial1916-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1918 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1918\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1917-1918\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1918-0\" name=\"form_fields[serial1918]\"> <label for=\"form-field-serial1918-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1920 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1920\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1919-1920\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1920-0\" name=\"form_fields[serial1920]\"> <label for=\"form-field-serial1920-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1922 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1922\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1921-1922\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1922-0\" name=\"form_fields[serial1922]\"> <label for=\"form-field-serial1922-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1924 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1924\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1923-1924\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1924-0\" name=\"form_fields[serial1924]\"> <label for=\"form-field-serial1924-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1926 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1926\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1925-1926\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1926-0\" name=\"form_fields[serial1926]\"> <label for=\"form-field-serial1926-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1928 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1928\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1927-1928\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1928-0\" name=\"form_fields[serial1928]\"> <label for=\"form-field-serial1928-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1930 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1930\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1929-1930\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1930-0\" name=\"form_fields[serial1930]\"> <label for=\"form-field-serial1930-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1932 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1932\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1931-1932\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1932-0\" name=\"form_fields[serial1932]\"> <label for=\"form-field-serial1932-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1934 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1934\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1933-1934\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1934-0\" name=\"form_fields[serial1934]\"> <label for=\"form-field-serial1934-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1936 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1936\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1935-1936\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1936-0\" name=\"form_fields[serial1936]\"> <label for=\"form-field-serial1936-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1938 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1938\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1937-1938\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1938-0\" name=\"form_fields[serial1938]\"> <label for=\"form-field-serial1938-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1940 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1940\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1939-1940\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1940-0\" name=\"form_fields[serial1940]\"> <label for=\"form-field-serial1940-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1948 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1948\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1941-1948\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1948-0\" name=\"form_fields[serial1948]\"> <label for=\"form-field-serial1948-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1950 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1950\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1949-1950\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1950-0\" name=\"form_fields[serial1950]\"> <label for=\"form-field-serial1950-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1952 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1952\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1951-1952\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1952-0\" name=\"form_fields[serial1952]\"> <label for=\"form-field-serial1952-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1954 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1954\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1953-1954\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1954-0\" name=\"form_fields[serial1954]\"> <label for=\"form-field-serial1954-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1956 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1956\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1955-1956\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1956-0\" name=\"form_fields[serial1956]\"> <label for=\"form-field-serial1956-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1958 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1958\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1957-1958\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1958-0\" name=\"form_fields[serial1958]\"> <label for=\"form-field-serial1958-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1960 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1960\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1959-1960\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1960-0\" name=\"form_fields[serial1960]\"> <label for=\"form-field-serial1960-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1962 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1962\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1961-1962\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1962-0\" name=\"form_fields[serial1962]\"> <label for=\"form-field-serial1962-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1964 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1964\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1963-1964\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1964-0\" name=\"form_fields[serial1964]\"> <label for=\"form-field-serial1964-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1966 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1966\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1965-1966\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1966-0\" name=\"form_fields[serial1966]\"> <label for=\"form-field-serial1966-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1968 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1968\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1967-1968\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1968-0\" name=\"form_fields[serial1968]\"> <label for=\"form-field-serial1968-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1970 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1970\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1969-1970\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1970-0\" name=\"form_fields[serial1970]\"> <label for=\"form-field-serial1970-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1971 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1971\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1971\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1971-0\" name=\"form_fields[serial1971]\"> <label for=\"form-field-serial1971-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1972 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1972\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1972\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1972-0\" name=\"form_fields[serial1972]\"> <label for=\"form-field-serial1972-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1973 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1973\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1973\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1973-0\" name=\"form_fields[serial1973]\"> <label for=\"form-field-serial1973-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1974 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1974\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1974\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1974-0\" name=\"form_fields[serial1974]\"> <label for=\"form-field-serial1974-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1975 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1975\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1975\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1975-0\" name=\"form_fields[serial1975]\"> <label for=\"form-field-serial1975-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1976 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1976\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1976\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1976-0\" name=\"form_fields[serial1976]\"> <label for=\"form-field-serial1976-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1977 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1977\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1977\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1977-0\" name=\"form_fields[serial1977]\"> <label for=\"form-field-serial1977-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1978 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1978\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1978\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1978-0\" name=\"form_fields[serial1978]\"> <label for=\"form-field-serial1978-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1979 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1979\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1979\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1979-0\" name=\"form_fields[serial1979]\"> <label for=\"form-field-serial1979-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1980 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1980\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1980\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1980-0\" name=\"form_fields[serial1980]\"> <label for=\"form-field-serial1980-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1981 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1981\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1981\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1981-0\" name=\"form_fields[serial1981]\"> <label for=\"form-field-serial1981-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1982 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1982\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1982\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1982-0\" name=\"form_fields[serial1982]\"> <label for=\"form-field-serial1982-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1983 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1983\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1983\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1983-0\" name=\"form_fields[serial1983]\"> <label for=\"form-field-serial1983-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1984 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1984\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1984\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1984-0\" name=\"form_fields[serial1984]\"> <label for=\"form-field-serial1984-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1985 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1985\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1985\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1985-0\" name=\"form_fields[serial1985]\"> <label for=\"form-field-serial1985-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1986 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1986\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1986\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1986-0\" name=\"form_fields[serial1986]\"> <label for=\"form-field-serial1986-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1987 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1987\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1987\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1987-0\" name=\"form_fields[serial1987]\"> <label for=\"form-field-serial1987-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1988 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1988\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1988\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1988-0\" name=\"form_fields[serial1988]\"> <label for=\"form-field-serial1988-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1989 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1989\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1989\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1989-0\" name=\"form_fields[serial1989]\"> <label for=\"form-field-serial1989-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1990 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1990\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1990\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1990-0\" name=\"form_fields[serial1990]\"> <label for=\"form-field-serial1990-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1991 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1991\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1991\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1991-0\" name=\"form_fields[serial1991]\"> <label for=\"form-field-serial1991-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1992 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1992\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1992\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1992-0\" name=\"form_fields[serial1992]\"> <label for=\"form-field-serial1992-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1993 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1993\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1993\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1993-0\" name=\"form_fields[serial1993]\"> <label for=\"form-field-serial1993-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1994 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1994\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1994\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1994-0\" name=\"form_fields[serial1994]\"> <label for=\"form-field-serial1994-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1995 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1995\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1995\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1995-0\" name=\"form_fields[serial1995]\"> <label for=\"form-field-serial1995-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1996 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1996\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1996\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1996-0\" name=\"form_fields[serial1996]\"> <label for=\"form-field-serial1996-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1997 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1997\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1997\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1997-0\" name=\"form_fields[serial1997]\"> <label for=\"form-field-serial1997-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1998 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1998\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1998\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1998-0\" name=\"form_fields[serial1998]\"> <label for=\"form-field-serial1998-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial1999 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial1999\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t1999\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial1999-0\" name=\"form_fields[serial1999]\"> <label for=\"form-field-serial1999-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2000 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2000\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2000\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2000-0\" name=\"form_fields[serial2000]\"> <label for=\"form-field-serial2000-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2001 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2001\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2001\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2001-0\" name=\"form_fields[serial2001]\"> <label for=\"form-field-serial2001-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2002 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2002\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2002\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2002-0\" name=\"form_fields[serial2002]\"> <label for=\"form-field-serial2002-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2003 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2003\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2003\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2003-0\" name=\"form_fields[serial2003]\"> <label for=\"form-field-serial2003-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2004 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2004\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2004\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2004-0\" name=\"form_fields[serial2004]\"> <label for=\"form-field-serial2004-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2005 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2005\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2005\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2005-0\" name=\"form_fields[serial2005]\"> <label for=\"form-field-serial2005-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2006 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2006\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2006\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2006-0\" name=\"form_fields[serial2006]\"> <label for=\"form-field-serial2006-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2007 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2007\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2007\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2007-0\" name=\"form_fields[serial2007]\"> <label for=\"form-field-serial2007-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2008 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2008\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2008\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2008-0\" name=\"form_fields[serial2008]\"> <label for=\"form-field-serial2008-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2009 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2009\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2009\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2009-0\" name=\"form_fields[serial2009]\"> <label for=\"form-field-serial2009-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2010 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2010\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2010\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2010-0\" name=\"form_fields[serial2010]\"> <label for=\"form-field-serial2010-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2011 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2011\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2011\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2011-0\" name=\"form_fields[serial2011]\"> <label for=\"form-field-serial2011-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2012 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2012\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2012\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2012-0\" name=\"form_fields[serial2012]\"> <label for=\"form-field-serial2012-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2013 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2013\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2013\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2013-0\" name=\"form_fields[serial2013]\"> <label for=\"form-field-serial2013-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2014 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2014\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2014\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2014-0\" name=\"form_fields[serial2014]\"> <label for=\"form-field-serial2014-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2015 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2015\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2015\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2015-0\" name=\"form_fields[serial2015]\"> <label for=\"form-field-serial2015-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2016 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2016\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2016\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2016-0\" name=\"form_fields[serial2016]\"> <label for=\"form-field-serial2016-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2017 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2017\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2017\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2017-0\" name=\"form_fields[serial2017]\"> <label for=\"form-field-serial2017-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-serial2018 elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-serial2018\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t2018\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"\" id=\"form-field-serial2018-0\" name=\"form_fields[serial2018]\"> <label for=\"form-field-serial2018-0\"><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-xs\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed54191 elementor-widget elementor-widget-html\" data-id=\"ed54191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\nlet showThisFieldIf = {\r\n    serial1885: {\r\n        serialnumber: [1],\r\n    },\r\n    serial1890: {\r\n        serialnumber: [2],\r\n    },\r\n    serial1892: {\r\n        serialnumber: [3],\r\n    },\r\n    serial1894: {\r\n        serialnumber: [4],\r\n    },\r\n    serial1896: {\r\n        serialnumber: [5],\r\n    },\r\n    serial1898: {\r\n        serialnumber: [6],\r\n    },\r\n    serial1900: {\r\n        serialnumber: [7],\r\n    },\r\n    serial1902: {\r\n        serialnumber: [8],\r\n    },\r\n    serial1904: {\r\n        serialnumber: [9],\r\n    },\r\n    serial1906: {\r\n        serialnumber: [10],\r\n    },\r\n    serial1908: {\r\n        serialnumber: [11],\r\n    },\r\n    serial1910: {\r\n        serialnumber: [12],\r\n    },\r\n    serial1912: {\r\n        serialnumber: [13],\r\n    },\r\n    serial1914: {\r\n        serialnumber: [14],\r\n    },\r\n    serial1916: {\r\n        serialnumber: [15],\r\n    },\r\n    serial1918: {\r\n        serialnumber: [16],\r\n    },\r\n    serial1920: {\r\n        serialnumber: [17],\r\n    },\r\n    serial1922: {\r\n        serialnumber: [18],\r\n    },\r\n    serial1924: {\r\n        serialnumber: [19],\r\n    },\r\n    serial1926: {\r\n        serialnumber: [20],\r\n    },\r\n    serial1928: {\r\n        serialnumber: [21],\r\n    },\r\n    serial1930: {\r\n        serialnumber: [22],\r\n    },\r\n    serial1932: {\r\n        serialnumber: [23],\r\n    },\r\n    serial1934: {\r\n        serialnumber: [24],\r\n    },\r\n    serial1936: {\r\n        serialnumber: [25],\r\n    },\r\n    serial1938: {\r\n        serialnumber: [26],\r\n    },\r\n    serial1940: {\r\n        serialnumber: [27],\r\n    },\r\n    serial1948: {\r\n        serialnumber: [28],\r\n    },\r\n    serial1950: {\r\n        serialnumber: [29],\r\n    },\r\n    serial1952: {\r\n        serialnumber: [30],\r\n    },\r\n    serial1954: {\r\n        serialnumber: [31],\r\n    },\r\n    serial1956: {\r\n        serialnumber: [32],\r\n    },\r\n    serial1958: {\r\n        serialnumber: [33],\r\n    },\r\n    serial1960: {\r\n        serialnumber: [34],\r\n    },\r\n    serial1962: {\r\n        serialnumber: [35],\r\n    },\r\n    serial1964: {\r\n        serialnumber: [36],\r\n    },\r\n    serial1966: {\r\n        serialnumber: [37],\r\n    },\r\n    serial1968: {\r\n        serialnumber: [38],\r\n    },\r\n    serial1970: {\r\n        serialnumber: [39],\r\n    },\r\n    serial1971: {\r\n        serialnumber: [40],\r\n    },\r\n    serial1972: {\r\n        serialnumber: [41],\r\n    },\r\n    serial1973: {\r\n        serialnumber: [42],\r\n    },\r\n    serial1974: {\r\n        serialnumber: [43],\r\n    },\r\n    serial1975: {\r\n        serialnumber: [44],\r\n    },\r\n    serial1976: {\r\n        serialnumber: [45],\r\n    },\r\n    serial1977: {\r\n        serialnumber: [46],\r\n    },\r\n    serial1978: {\r\n        serialnumber: [47],\r\n    },\r\n    serial1979: {\r\n        serialnumber: [48],\r\n    },\r\n    serial1980: {\r\n        serialnumber: [49],\r\n    },\r\n    serial1981: {\r\n        serialnumber: [50],\r\n    },\r\n    serial1982: {\r\n        serialnumber: [51],\r\n    },\r\n    serial1983: {\r\n        serialnumber: [52],\r\n    },\r\n    serial1984: {\r\n        serialnumber: [53],\r\n    },\r\n    serial1985: {\r\n        serialnumber: [54],\r\n    },\r\n    serial1986: {\r\n        serialnumber: [55],\r\n    },\r\n    serial1987: {\r\n        serialnumber: [56],\r\n    },\r\n    serial1988: {\r\n        serialnumber: [57],\r\n    },\r\n    serial1989: {\r\n        serialnumber: [58],\r\n    },\r\n    serial1990: {\r\n        serialnumber: [59],\r\n    },\r\n    serial1991: {\r\n        serialnumber: [60],\r\n    },\r\n    serial1992: {\r\n        serialnumber: [61],\r\n    },\r\n    serial1993: {\r\n        serialnumber: [62],\r\n    },\r\n    serial1994: {\r\n        serialnumber: [63],\r\n    },\r\n    serial1995: {\r\n        serialnumber: [64],\r\n    },\r\n    serial1996: {\r\n        serialnumber: [65],\r\n    },\r\n    serial1997: {\r\n        serialnumber: [66],\r\n    },\r\n    serial1998: {\r\n        serialnumber: [67],\r\n    },\r\n    serial1999: {\r\n        serialnumber: [68],\r\n    },\r\n    serial2000: {\r\n        serialnumber: [69],\r\n    },\r\n    serial2001: {\r\n        serialnumber: [70],\r\n    },\r\n    serial2002: {\r\n        serialnumber: [71],\r\n    },\r\n    serial2003: {\r\n        serialnumber: [72],\r\n    },\r\n    serial2004: {\r\n        serialnumber: [73],\r\n    },\r\n    serial2005: {\r\n        serialnumber: [74],\r\n    },\r\n    serial2006: {\r\n        serialnumber: [75],\r\n    },\r\n    serial2007: {\r\n        serialnumber: [76],\r\n    },\r\n    serial2008: {\r\n        serialnumber: [77],\r\n    },\r\n    serial2009: {\r\n        serialnumber: [78],\r\n    },\r\n    serial2010: {\r\n        serialnumber: [79],\r\n    },\r\n    serial2011: {\r\n        serialnumber: [80],\r\n    },\r\n    serial2012: {\r\n        serialnumber: [81],\r\n    },\r\n    serial2013: {\r\n        serialnumber: [82],\r\n    },\r\n    serial2014: {\r\n        serialnumber: [83],\r\n    },\r\n    serial2015: {\r\n        serialnumber: [84],\r\n    },\r\n    serial2016: {\r\n        serialnumber: [85],\r\n    },\r\n    serial2017: {\r\n        serialnumber: [86],\r\n    },\r\n    serial2018: {\r\n        serialnumber: [87],\r\n    },\r\n}\r\ndocument.addEventListener('DOMContentLoaded', function () {\r\nfunction testLogic() {\r\nfor (const [conditionalInputID, condition] of Object.entries(showThisFieldIf)) {\r\nlet conditionalInput = setInputsElemArray(conditionalInputID);\r\nlet match = true;\r\nfor (const [conditionID, conditionValues] of Object.entries(condition)) {\r\nlet inputs = setInputsElemArray(conditionID);\r\nlet selectedInputs = [];\r\ninputs.forEach((input, i) => { if (input.checked) { selectedInputs.push(i); } });\r\nif (inputs[0].tagName == 'SELECT') {\r\nselectedInputs.push(inputs[0].selectedIndex);\r\n}\r\nlet adjustedConditionValues = conditionValues.map(e => e - 1);\r\nif (!(adjustedConditionValues.every(condition => selectedInputs.indexOf(condition) > -1))) {\r\nmatch = false;\r\n}\r\n};\r\nif (match) {\r\nconditionalInput.forEach(e => e.closest('.elementor-field-group').style.display = \"block\")\r\n} else {\r\nconditionalInput.forEach(e => e.closest('.elementor-field-group').style.display = \"none\")\r\n}\r\n}\r\n}\r\ntestLogic();\r\n\r\n\/* Add event listeners *\/\r\nfor (const [conditionalInputID, condition] of Object.entries(showThisFieldIf)) {\r\nfor (const [conditionID, conditionValues] of Object.entries(condition)) {\r\nlet inputs = setInputsElemArray(conditionID);\r\ninputs.forEach(input => {\r\ninput.addEventListener('input', function () {\r\ntestLogic();\r\n})\r\n})\r\n}\r\n}\r\n\r\nfunction setInputsElemArray(ID) {\r\nlet selectors = `[name=\"form_fields[${ID}]\"]`;\r\nlet inputs = Array.from(document.querySelectorAll(selectors));\r\nif (!inputs.length) {\r\nselectors = `[name=\"form_fields[${ID}][]\"]`;\r\ninputs = Array.from(document.querySelectorAll(selectors));\r\n}\r\nreturn inputs;\r\n}\r\n});\r\n\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9687e58\" data-id=\"9687e58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa8f842 elementor-widget elementor-widget-heading\" data-id=\"aa8f842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Brosch\u00fcre herunterladen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-838307c elementor-widget elementor-widget-text-editor\" data-id=\"838307c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAlle hier aufgef\u00fchrten Informationen k\u00f6nnen Sie auch zusammengefasst in unserer Brosch\u00fcre &#8222;Werterhalt und Pflege&#8220; im Downloadbereich herunterladen:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0578bd elementor-widget elementor-widget-spacer\" data-id=\"a0578bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f3be3 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"66f3be3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/www.schimmel-pianos.de\/downloads\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Downloads<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Werterhalt &amp; Pflege Wertvolle Tips f\u00fcr die Pflege und den Werterhalt Ihres Schimmel Pianos Ein markanter Spruch unseres Firmengr\u00fcnders Wilhelm Schimmel war: \u201eAm Ende sind unsere Instrumente immer nur so gut, wie der letzte Service Klaviertechniker, der daran gearbeitet hat\u201c. In diesem Satz steckt viel Wahres, denn hochwertige Qualit\u00e4t braucht zum Erhalt auch einen hochwertigen [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":11472,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-8725","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Werterhalt und Pflege - Schimmel Piano<\/title>\n<meta name=\"description\" content=\"\u201eAm Ende sind unsere Instrumente immer nur so gut, wie der letzte Service Klaviertechniker, der daran gearbeitet hat\u201c. In diesem Satz steckt viel Wahres, denn hochwertige Qualit\u00e4t braucht zum Erhalt auch einen hochwertigen After Sales Service und eine ausgezeichnete Pflege.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schimmel-pianos.de\/fr\/prevention-et-soin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Werterhalt und Pflege - Schimmel Piano\" \/>\n<meta property=\"og:description\" content=\"\u201eAm Ende sind unsere Instrumente immer nur so gut, wie der letzte Service Klaviertechniker, der daran gearbeitet hat\u201c. In diesem Satz steckt viel Wahres, denn hochwertige Qualit\u00e4t braucht zum Erhalt auch einen hochwertigen After Sales Service und eine ausgezeichnete Pflege.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schimmel-pianos.de\/fr\/prevention-et-soin\/\" \/>\n<meta property=\"og:site_name\" content=\"Schimmel Piano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SchimmelPianos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T08:42:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SchimmelPianos\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/\",\"url\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/\",\"name\":\"Werterhalt und Pflege - Schimmel Piano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/08_Pflege_und_Werterhalt_Titelbild_2.webp\",\"datePublished\":\"2022-10-25T08:08:26+00:00\",\"dateModified\":\"2025-07-07T08:42:12+00:00\",\"description\":\"\u201eAm Ende sind unsere Instrumente immer nur so gut, wie der letzte Service Klaviertechniker, der daran gearbeitet hat\u201c. In diesem Satz steckt viel Wahres, denn hochwertige Qualit\u00e4t braucht zum Erhalt auch einen hochwertigen After Sales Service und eine ausgezeichnete Pflege.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/08_Pflege_und_Werterhalt_Titelbild_2.webp\",\"contentUrl\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/08_Pflege_und_Werterhalt_Titelbild_2.webp\",\"width\":2500,\"height\":1500,\"caption\":\"Pflege und Werterhalt Titelbild\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/werterhalt-und-pflege\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Werterhalt und Pflege\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/\",\"name\":\"Schimmel Pianos\",\"description\":\"Crafting pianos with passion in Germany - since 1885.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/#organization\"},\"alternateName\":\"Schimmel Piano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/#organization\",\"name\":\"Wilhelm Schimmel Pianofortefabrik GmbH\",\"url\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Schimmel_Logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Schimmel_Logo.webp\",\"width\":150,\"height\":50,\"caption\":\"Wilhelm Schimmel Pianofortefabrik GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schimmel-pianos.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SchimmelPianos\",\"https:\\\/\\\/x.com\\\/SchimmelPianos\",\"https:\\\/\\\/www.instagram.com\\\/schimmelpianos\\\/\",\"https:\\\/\\\/m.youtube.com\\\/c\\\/SchimmelPianosOfficial\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9servation et entretien - Piano Schimmel","description":"\u00ab Notre instrument est toujours aussi bons apr\u00e8s que le dernier technicien ait travaill\u00e9 dessus \u00bb. Une qualit\u00e9 d'instrument sup\u00e9rieure n\u00e9cessite \u00e9galement un service apr\u00e8s-vente de qualit\u00e9 et une rigueur d'entretien pour \u00eatre maintenue \u00e0 mon plein potentiel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schimmel-pianos.de\/fr\/prevention-et-soin\/","og_locale":"fr_FR","og_type":"article","og_title":"Werterhalt und Pflege - Schimmel Piano","og_description":"\u201eAm Ende sind unsere Instrumente immer nur so gut, wie der letzte Service Klaviertechniker, der daran gearbeitet hat\u201c. In diesem Satz steckt viel Wahres, denn hochwertige Qualit\u00e4t braucht zum Erhalt auch einen hochwertigen After Sales Service und eine ausgezeichnete Pflege.","og_url":"https:\/\/www.schimmel-pianos.de\/fr\/prevention-et-soin\/","og_site_name":"Schimmel Piano","article_publisher":"https:\/\/www.facebook.com\/SchimmelPianos","article_modified_time":"2025-07-07T08:42:12+00:00","og_image":[{"width":2500,"height":1500,"url":"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@SchimmelPianos","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/","url":"https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/","name":"Pr\u00e9servation et entretien - Piano Schimmel","isPartOf":{"@id":"https:\/\/www.schimmel-pianos.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/#primaryimage"},"image":{"@id":"https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2.webp","datePublished":"2022-10-25T08:08:26+00:00","dateModified":"2025-07-07T08:42:12+00:00","description":"\u00ab Notre instrument est toujours aussi bons apr\u00e8s que le dernier technicien ait travaill\u00e9 dessus \u00bb. Une qualit\u00e9 d'instrument sup\u00e9rieure n\u00e9cessite \u00e9galement un service apr\u00e8s-vente de qualit\u00e9 et une rigueur d'entretien pour \u00eatre maintenue \u00e0 mon plein potentiel.","breadcrumb":{"@id":"https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/#primaryimage","url":"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2.webp","contentUrl":"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2023\/01\/08_Pflege_und_Werterhalt_Titelbild_2.webp","width":2500,"height":1500,"caption":"Pflege und Werterhalt Titelbild"},{"@type":"BreadcrumbList","@id":"https:\/\/www.schimmel-pianos.de\/werterhalt-und-pflege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.schimmel-pianos.de\/"},{"@type":"ListItem","position":2,"name":"Werterhalt und Pflege"}]},{"@type":"WebSite","@id":"https:\/\/www.schimmel-pianos.de\/en\/#website","url":"https:\/\/www.schimmel-pianos.de\/en\/","name":"Pianos Schimmel","description":"Fabriquer des pianos en Allemagne avec passion - depuis 1885","publisher":{"@id":"https:\/\/www.schimmel-pianos.de\/en\/#organization"},"alternateName":"Schimmel Piano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schimmel-pianos.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.schimmel-pianos.de\/en\/#organization","name":"Wilhelm Schimmel Pianofortefabrik GmbH","url":"https:\/\/www.schimmel-pianos.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.schimmel-pianos.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/04\/Schimmel_Logo.webp","contentUrl":"https:\/\/www.schimmel-pianos.de\/wp-content\/uploads\/2022\/04\/Schimmel_Logo.webp","width":150,"height":50,"caption":"Wilhelm Schimmel Pianofortefabrik GmbH"},"image":{"@id":"https:\/\/www.schimmel-pianos.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SchimmelPianos","https:\/\/x.com\/SchimmelPianos","https:\/\/www.instagram.com\/schimmelpianos\/","https:\/\/m.youtube.com\/c\/SchimmelPianosOfficial"]}]}},"_links":{"self":[{"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/pages\/8725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/comments?post=8725"}],"version-history":[{"count":5,"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/pages\/8725\/revisions"}],"predecessor-version":[{"id":20884,"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/pages\/8725\/revisions\/20884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/media\/11472"}],"wp:attachment":[{"href":"https:\/\/www.schimmel-pianos.de\/fr\/wp-json\/wp\/v2\/media?parent=8725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}